{"id":10261,"date":"2023-01-03T17:04:58","date_gmt":"2023-01-03T16:04:58","guid":{"rendered":"https:\/\/pecho.hr\/stampaggio-a-iniezione\/"},"modified":"2023-07-20T20:25:37","modified_gmt":"2023-07-20T18:25:37","slug":"stampaggio-a-iniezione","status":"publish","type":"page","link":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/","title":{"rendered":"Stampaggio a iniezione"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.18.0&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_header title=&#8221;Stampaggio a iniezione&#8221; text_orientation=&#8221;center&#8221; button_one_text=&#8221;Invia la richiesta&#8221; button_one_url=&#8221;https:\/\/pecho.hr\/it\/invia-la-richiesta\/&#8221; _builder_version=&#8221;4.20.4&#8243; title_font=&#8221;||||||||&#8221; title_font_size=&#8221;80px&#8221; title_line_height=&#8221;1.2em&#8221; subhead_font=&#8221;||||||||&#8221; subhead_font_size=&#8221;25px&#8221; background_color=&#8221;rgba(255, 255, 255, 0)&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(252,97,0,0.49) 0%|rgba(48,58,109,0.84) 38%|rgba(48,58,109,0.18) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/RF8Eg2qV_2x.jpg&#8221; parallax=&#8221;on&#8221; custom_button_one=&#8221;on&#8221; button_one_text_size=&#8221;18px&#8221; button_one_bg_color=&#8221;#FC6100&#8243; button_one_border_width=&#8221;0px&#8221; button_one_letter_spacing=&#8221;2px&#8221; button_one_font=&#8221;|||on|||||&#8221; button_one_use_icon=&#8221;off&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;14vh||15vh||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;75px||75px|&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; title_font_size_tablet=&#8221;&#8221; title_font_size_phone=&#8221;34px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; button_one_text_size_tablet=&#8221;&#8221; button_one_text_size_phone=&#8221;14px&#8221; button_one_text_size_last_edited=&#8221;on|phone&#8221; box_shadow_style_button_one=&#8221;preset1&#8243; button_one_letter_spacing_hover=&#8221;2px&#8221; button_one_bg_color_hover=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;on&#8221; button_one_letter_spacing__hover=&#8221;2px&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;on&#8221; button_one_bg_color__hover=&#8221;#000000&#8243; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;64px|0px|0px|0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||30px|&#8221; custom_margin_tablet=&#8221;||30px|&#8221; custom_margin_phone=&#8221;-50px||-6px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Che cos&#8217;\u00e8 lo stampaggio a iniezione della plastica?<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#000000&#8243; divider_position=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;15%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.20.2&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Lo stampaggio a iniezione di plastica \u00e8 un processo di produzione di parti in plastica che utilizza masse plastiche che si fondono sotto alta pressione ed energia termica. Questa tecnologia viene utilizzata per produrre vari tipi di componenti, tra cui custodie per dispositivi elettronici, giocattoli, elettrodomestici, automobili e altro ancora.<\/p>\n<p>Esistono diversi metodi di stampaggio a iniezione della plastica, tra cui lo stampaggio a iniezione termoplastica, la termoformatura e lo stampaggio a iniezione. Nello stampaggio a iniezione termoplastica, la massa plastica viene fusa in un cilindro e iniettata ad alta pressione attraverso un piccolo alloggiamento aperto nello stampo. Quando si raffredda, la massa si indurisce a forma di stampo.<\/p>\n<p>La massa plastica viene inserita in uno stampo ad alta pressione e sottoposta a trattamento termico nella termoformatura. When it cools, the mass hardens into the shape of a mould.<\/p>\n<p>Lo stampaggio a iniezione viene utilizzato per produrre parti con pi\u00f9 strati e pi\u00f9 colori. La massa plastica viene fusa in un cilindro e iniettata nello stampo durante questo processo. Quando si raffredda, la massa si indurisce assumendo la forma di uno stampo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][dsm_perspective_image src=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/2.jpg&#8221; title_text=&#8221;2&#8243; dsm_rotate_y=&#8221;9deg&#8221; dsm_rotate_x=&#8221;2deg&#8221; dsm_rotate_z=&#8221;5deg&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;154px|||||&#8221; custom_padding_tablet=&#8221;154px|||||&#8221; custom_padding_phone=&#8221;57px||||false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/dsm_perspective_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;64px|0px|0px|0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][dsm_perspective_image src=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/plastika-bijela-podloga-9.jpeg&#8221; title_text=&#8221;plastica&#8221; perspective=&#8221;1239px&#8221; dsm_rotate_y=&#8221;14deg&#8221; dsm_rotate_x=&#8221;-3deg&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-39px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;130px|||61px|false|false&#8221; custom_padding_tablet=&#8221;130px|||61px|false|false&#8221; custom_padding_phone=&#8221;0px||14px|0px|false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; filter_invert=&#8221;1%&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/dsm_perspective_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;||30px||false|false&#8221; custom_margin_phone=&#8221;||0px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;21px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Tecnologia e strumenti<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#000000&#8243; divider_position=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;15%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.20.2&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il nostro stabilimento di produzione utilizza i macchinari pi\u00f9 avanzati per creare un vantaggio competitivo e fornire ai nostri clienti il miglior servizio possibile.<br \/>Inoltre, il nostro team di esperti offre servizi di progettazione e produzione di strumenti per lo stampaggio a iniezione di plastica per soddisfare le esigenze individuali dei clienti.<\/p>\n<p>La nostra offerta comprende anche la consulenza nelle fasi iniziali del processo produttivo, tra cui l&#8217;aiuto nella scelta dei materiali migliori e il supporto nella realizzazione degli utensili.<br \/>Che si tratti di prototipi o di grandi serie, ti offriamo tutto in un unico posto.<\/p>\n<p>Insieme ai nostri clienti, sviluppiamo prodotti dall&#8217;idea al prodotto finito, il che ci permette di essere competitivi e innovativi.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.19.5&#8243; custom_padding=&#8221;56px||||false|false&#8221; custom_padding_tablet=&#8221;27px||||false|false&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;custom_shadow_column&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||25px|&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2022\/10\/Triangle-1.png&#8221; title_text=&#8221;luce&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.18.0&#8243; background_image=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2023\/01\/lampa.jpg&#8221; background_position=&#8221;bottom_center&#8221; custom_padding=&#8221;250px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.18.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;||||||||&#8221; header_3_font_size=&#8221;30px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||20px|&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Idea di prodotto<\/h3>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#000000&#8243; divider_position=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;25%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||25px|&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|25px||25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Ogni progetto di successo inizia con una buona pianificazione. In questa prima fase, il nostro team di esperti si dedicher\u00e0 alla tua idea<\/span><span>e la trasformer\u00e0 in un prodotto di qualit\u00e0 superiore.<\/span><\/p>\n<p><span>Contattaci in tutta tranquillit\u00e0.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;custom_shadow_column&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||25px|&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2022\/10\/Triangle-1.png&#8221; title_text=&#8221;22&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.19.5&#8243; background_image=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/22.jpg&#8221; background_position=&#8221;bottom_center&#8221; custom_padding=&#8221;250px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.19.5&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;||||||||&#8221; header_3_font_size=&#8221;30px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||20px|&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Costruzione di utensili<\/h3>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#000000&#8243; divider_position=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;25%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||25px|&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|25px||25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Dopo aver deciso il prodotto da realizzare, \u00e8 necessario creare uno strumento o uno stampo che viene utilizzato nel processo di produzione dello stampaggio a iniezione di plastica. Creeremo uno strumento per realizzare il tuo prodotto con precisione e qualit\u00e0. La nostra esperienza e le nostre conoscenze rendono questa fase facile e veloce per te.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; module_class=&#8221;custom_shadow_column&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||25px|&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2022\/10\/Triangle-1.png&#8221; title_text=&#8221;24&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.19.5&#8243; background_image=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/24.jpg&#8221; background_position=&#8221;bottom_center&#8221; custom_padding=&#8221;250px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.19.5&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;||||||||&#8221; header_3_font_size=&#8221;30px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||20px|&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Produzione<\/h3>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#000000&#8243; divider_position=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;25%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||25px|&#8221; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.20.2&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;|25px||25px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Ora che abbiamo finito di realizzare gli strumenti per lo stampaggio a iniezione della plastica, possiamo dedicarci alla produzione delle quantit\u00e0 desiderate. Utilizziamo i macchinari pi\u00f9 avanzati <\/span><span>per lo stampaggio a iniezione della plastica, per garantire che il tuo prodotto sia di alta qualit\u00e0 e costante in ogni lotto. <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_masonry_gallery gallery_ids=&#8221;9187,9285,9284,9154,9156,9161,9159,9153,9157&#8243; use_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_masonry_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#000000&#8243; custom_padding=&#8221;0px|0px|0px|0px&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Vuoi scoprire cosa possiamo produrre per te?&#8221; button_url=&#8221;#&#8221; _builder_version=&#8221;4.18.0&#8243; background_color=&#8221;#000000&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_bg_color=&#8221;#FC6100&#8243; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;#ffffff&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; animation_style=&#8221;zoom&#8221; button_text_color_hover=&#8221;#000000&#8243; button_bg_color_hover=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#000000&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;#ffffff&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(255,255,255,0.9) 0%|rgba(255,255,255,0.9) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(255,255,255,0.9)&#8221; background_color_gradient_end=&#8221;rgba(255,255,255,0.9)&#8221; background_image=&#8221;https:\/\/pecho.hr\/wp-content\/uploads\/2022\/10\/pexels-photo.jpg&#8221; global_module=&#8221;10410&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221; locked=&#8221;off&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Contattaci!<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Non esitare, non esitare a contattarci!<\/p>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Indirizzo&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe074;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;24px&#8221; _builder_version=&#8221;4.18.0&#8243; header_font=&#8221;||||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; max_width=&#8221;80%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;24px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Josipa Jela\u010di\u0107a 135<\/span><br \/><span>10430 Samobor<\/span><br \/><span>Croazia | Hrvatska<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Email&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;24px&#8221; _builder_version=&#8221;4.18.0&#8243; header_font=&#8221;||||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; max_width=&#8221;80%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;24px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>info@pecho.hr<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Numero di telefono&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_color=&#8221;#000000&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;24px&#8221; _builder_version=&#8221;4.18.0&#8243; header_font=&#8221;||||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; max_width=&#8221;80%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;24px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Tel: 01\/ 3360 386<br \/>Fax: 01\/ 3362 869<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Inviaci un messaggio!<\/h2>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;Pecho|Pecho-0&#8243; email=&#8221;eosmanagic@gmail.com&#8221; custom_message=&#8221;Po\u0161tovani, ||et_pb_line_break_holder||||et_pb_line_break_holder||dobili ste poruku s web stranice pecho.hr.||et_pb_line_break_holder||||et_pb_line_break_holder||Naziv: %%Name%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Tel.\/Mob: %%Phone%%||et_pb_line_break_holder||Poruka: %%Message%%&#8221; success_message=&#8221;Grazie!&#8221; module_id=&#8221;et_pb_contact_form_0&#8243; _builder_version=&#8221;4.20.4&#8243; form_field_background_color=&#8221;#f5f5f5&#8243; form_field_font=&#8221;||||||||&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#000000&#8243; button_font=&#8221;||||||||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; border_radii=&#8221;on|3px|3px|3px|3px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#000000&#8243; form_background_color=&#8221;#f5f5f5&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Nome&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.18.0&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Email&#8221; field_type=&#8221;email&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Phone&#8221; field_title=&#8221;Numero di telefono&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.20.4&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Messaggio&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.18.0&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che cos&#8217;\u00e8 lo stampaggio a iniezione della plastica?Lo stampaggio a iniezione di plastica \u00e8 un processo di produzione di parti in plastica che utilizza masse plastiche che si fondono sotto alta pressione ed energia termica. Questa tecnologia viene utilizzata per produrre vari tipi di componenti, tra cui custodie per dispositivi elettronici, giocattoli, elettrodomestici, automobili e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stampaggio a iniezione - Pecho<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stampaggio a iniezione - Pecho\" \/>\n<meta property=\"og:description\" content=\"Che cos&#039;\u00e8 lo stampaggio a iniezione della plastica?Lo stampaggio a iniezione di plastica \u00e8 un processo di produzione di parti in plastica che utilizza masse plastiche che si fondono sotto alta pressione ed energia termica. Questa tecnologia viene utilizzata per produrre vari tipi di componenti, tra cui custodie per dispositivi elettronici, giocattoli, elettrodomestici, automobili e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/\" \/>\n<meta property=\"og:site_name\" content=\"Pecho\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T18:25:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/66.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/\",\"url\":\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/\",\"name\":\"Stampaggio a iniezione - Pecho\",\"isPartOf\":{\"@id\":\"https:\/\/pecho.hr\/it\/#website\"},\"datePublished\":\"2023-01-03T16:04:58+00:00\",\"dateModified\":\"2023-07-20T18:25:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\/\/pecho.hr\/it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stampaggio a iniezione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pecho.hr\/it\/#website\",\"url\":\"https:\/\/pecho.hr\/it\/\",\"name\":\"Pecho\",\"description\":\"konfekcioniranje kablova i brizganje plastike\",\"publisher\":{\"@id\":\"https:\/\/pecho.hr\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pecho.hr\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pecho.hr\/it\/#organization\",\"name\":\"Pecho\",\"url\":\"https:\/\/pecho.hr\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/pecho.hr\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pecho.hr\/wp-content\/uploads\/2022\/11\/2.svg\",\"contentUrl\":\"https:\/\/pecho.hr\/wp-content\/uploads\/2022\/11\/2.svg\",\"width\":1,\"height\":1,\"caption\":\"Pecho\"},\"image\":{\"@id\":\"https:\/\/pecho.hr\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stampaggio a iniezione - Pecho","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/","og_locale":"it_IT","og_type":"article","og_title":"Stampaggio a iniezione - Pecho","og_description":"Che cos'\u00e8 lo stampaggio a iniezione della plastica?Lo stampaggio a iniezione di plastica \u00e8 un processo di produzione di parti in plastica che utilizza masse plastiche che si fondono sotto alta pressione ed energia termica. Questa tecnologia viene utilizzata per produrre vari tipi di componenti, tra cui custodie per dispositivi elettronici, giocattoli, elettrodomestici, automobili e [&hellip;]","og_url":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/","og_site_name":"Pecho","article_modified_time":"2023-07-20T18:25:37+00:00","og_image":[{"width":1000,"height":648,"url":"https:\/\/pecho.hr\/wp-content\/uploads\/2023\/02\/66.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/","url":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/","name":"Stampaggio a iniezione - Pecho","isPartOf":{"@id":"https:\/\/pecho.hr\/it\/#website"},"datePublished":"2023-01-03T16:04:58+00:00","dateModified":"2023-07-20T18:25:37+00:00","breadcrumb":{"@id":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pecho.hr\/it\/stampaggio-a-iniezione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/pecho.hr\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Stampaggio a iniezione"}]},{"@type":"WebSite","@id":"https:\/\/pecho.hr\/it\/#website","url":"https:\/\/pecho.hr\/it\/","name":"Pecho","description":"konfekcioniranje kablova i brizganje plastike","publisher":{"@id":"https:\/\/pecho.hr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pecho.hr\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/pecho.hr\/it\/#organization","name":"Pecho","url":"https:\/\/pecho.hr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pecho.hr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/pecho.hr\/wp-content\/uploads\/2022\/11\/2.svg","contentUrl":"https:\/\/pecho.hr\/wp-content\/uploads\/2022\/11\/2.svg","width":1,"height":1,"caption":"Pecho"},"image":{"@id":"https:\/\/pecho.hr\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/pages\/10261"}],"collection":[{"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/comments?post=10261"}],"version-history":[{"count":1,"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/pages\/10261\/revisions"}],"predecessor-version":[{"id":10413,"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/pages\/10261\/revisions\/10413"}],"wp:attachment":[{"href":"https:\/\/pecho.hr\/it\/wp-json\/wp\/v2\/media?parent=10261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}